{"id":272,"count":1,"description":"Una gu\u00eda para que encuentres qu\u00e9 ver en tu pr\u00f3ximo marat\u00f3n de pel\u00edculas. Descubre las pel\u00edculas que no te puedes perder.","link":"https:\/\/mysupernews.com\/es\/category\/pop-es\/streaming-cine\/","name":"Streaming &amp; Cine","slug":"streaming-cine","taxonomy":"category","parent":267,"meta":[],"_links":{"self":[{"href":"https:\/\/mysupernews.com\/es\/wp-json\/wp\/v2\/categories\/272","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mysupernews.com\/es\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/mysupernews.com\/es\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/mysupernews.com\/es\/wp-json\/wp\/v2\/categories\/267"}],"wp:post_type":[{"href":"https:\/\/mysupernews.com\/es\/wp-json\/wp\/v2\/posts?categories=272"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}